{"id":11547,"date":"2024-01-08T15:54:24","date_gmt":"2024-01-08T19:54:24","guid":{"rendered":"https:\/\/panoramatv.com.do\/?p=11547"},"modified":"2024-01-08T15:54:38","modified_gmt":"2024-01-08T19:54:38","slug":"wendys-entrega-donativo-a-fundacion-pedro-martinez","status":"publish","type":"post","link":"https:\/\/panoramatv.com.do\/index.php\/2024\/01\/08\/wendys-entrega-donativo-a-fundacion-pedro-martinez\/","title":{"rendered":"Wendy\u2019s entrega donativo a Fundaci\u00f3n Pedro Mart\u00ednez \u00a0"},"content":{"rendered":"\n<p><strong>Santo Domingo, Rep\u00fablica Dominicana. &#8211;<\/strong>&nbsp;La cadena internacional de hamburguesas Wendy\u2019s, operada en el pa\u00eds por Grupo Raya, culmin\u00f3 la 9ena entrega de su programa de ayuda a instituciones sociales, entregando un donativo de RD$837,876 a Pedro Mart\u00ednez Foundation, lo cual representa un 10% de los fondos generados por la venta de su men\u00fa infantil. &nbsp;<\/p>\n\n\n\n<p>Esta instituci\u00f3n tiene como misi\u00f3n servir como centro de apoyo comunitario para ni\u00f1os, ni\u00f1as, adolescentes y sus familias en zonas vulnerables, para que puedan acceder a una educaci\u00f3n forjada en valores imparti\u00e9ndoles programas de formaci\u00f3n acad\u00e9mica, deportiva, actividades culturales, servicios m\u00e9dicos, psicol\u00f3gicos y odontol\u00f3gicos. &nbsp;<\/p>\n\n\n\n<p>\u201cEn Pedro Martinez Foundation nos sentimos muy agradecidos y felices de esta importante colaboraci\u00f3n de Wendy\u2019s y de que nos hayan hecho parte de este programa \u201cKid\u2019s Meal\u201d. Esta es una gran oportunidad para nosotros continuar con nuestra misi\u00f3n de mejorar la calidad de vida de cientos de ni\u00f1os y ni\u00f1as a cumplir sus sue\u00f1os\u201d, expres\u00f3 la se\u00f1ora Carolina Cruz de Martinez, presidente de la fundaci\u00f3n. &nbsp;<\/p>\n\n\n\n<p>Wendy\u2019s lleva desde el 2017 implementando este programa que forma parte de su responsabilidad social corporativa logrando as\u00ed impactar a m\u00e1s de miles de ni\u00f1os a\u00f1o tras a\u00f1o. &nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/xco-images.nyc3.digitaloceanspaces.com\/panoramatv.com.do\/wp-content\/uploads\/2024\/01\/0-4-1024x683.jpg\" alt=\"\" class=\"wp-image-11548\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo, Rep\u00fablica Dominicana. &#8211;&nbsp;La cadena internacional de hamburguesas Wendy\u2019s, operada en el pa\u00eds por Grupo Raya, culmin\u00f3 la 9ena entrega de su programa de ayuda a instituciones sociales, entregando un donativo de RD$837,876 a Pedro Mart\u00ednez Foundation, lo cual representa un 10% de los fondos generados por la venta de su men\u00fa infantil. &nbsp; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11548,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[10],"tags":[877,2283,2282],"class_list":["post-11547","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-panorama-social","tag-panoramatv","tag-pedro-martinez","tag-wendys-2"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/panoramatv.com.do\/wp-content\/uploads\/2024\/01\/0-4-1125x750.jpg","jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/panoramatv.com.do\/index.php\/wp-json\/wp\/v2\/posts\/11547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/panoramatv.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/panoramatv.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/panoramatv.com.do\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/panoramatv.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=11547"}],"version-history":[{"count":0,"href":"https:\/\/panoramatv.com.do\/index.php\/wp-json\/wp\/v2\/posts\/11547\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/panoramatv.com.do\/index.php\/wp-json\/wp\/v2\/media\/11548"}],"wp:attachment":[{"href":"https:\/\/panoramatv.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=11547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/panoramatv.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=11547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/panoramatv.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=11547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}